{"id":398,"date":"2025-06-26T21:20:28","date_gmt":"2025-06-26T21:20:28","guid":{"rendered":"https:\/\/visioninforma.com\/portal\/?p=398"},"modified":"2025-06-26T21:20:28","modified_gmt":"2025-06-26T21:20:28","slug":"banco-nacional-de-panama-se-posiciona-como-referente-en-atraccion-y-desarrollo-de-talento-en-el-pais","status":"publish","type":"post","link":"https:\/\/visioninforma.com\/portal\/banco-nacional-de-panama-se-posiciona-como-referente-en-atraccion-y-desarrollo-de-talento-en-el-pais\/","title":{"rendered":"Banco Nacional de Panam\u00e1 se posiciona como referente en atracci\u00f3n y desarrollo de talento en el pa\u00eds"},"content":{"rendered":"\n<p>\u2022 Con este 2do. lugar en el ranking Merco Talento, la instituci\u00f3n bancaria sube tres posiciones si lo comparamos con el ranking 2024, donde alcanz\u00f3 la 5ta. posici\u00f3n.<\/p>\n\n\n\n<p>Panam\u00e1, 26 de junio de 2025. La primera instituci\u00f3n bancaria del pa\u00eds, consolida su liderazgo en la gesti\u00f3n del talento al posicionarse dentro del Top 3 de las empresas m\u00e1s atractivas para trabajar en Panam\u00e1, seg\u00fan la evaluaci\u00f3n Merco Talento. Este reconocimiento destaca su cultura organizacional s\u00f3lida y el compromiso integral de toda la instituci\u00f3n con el desarrollo de su gente. Banco Nacional de Panam\u00e1 alcanz\u00f3 el lugar n\u00famero 2, escalando 3 posiciones, ya que el a\u00f1o pasado logr\u00f3 la quinta posici\u00f3n.<\/p>\n\n\n\n<p>Merco Talento eval\u00faa la capacidad de las organizaciones para atraer y fidelizar al talento, a trav\u00e9s de una metodolog\u00eda de enfoque participativo de diversos grupos especializados respaldada por estudios independientes. En la edici\u00f3n 2025, Banco Nacional se ubic\u00f3 en 2do lugar, con una puntuaci\u00f3n de 8,693.<\/p>\n\n\n\n<p>Este reconocimiento es un reflejo de las pol\u00edticas internas de Banco Nacional de Panam\u00e1 establecidas en su Mapa Estrat\u00e9gico, en favor del desarrollo profesional, el bienestar del colaborador, y una cultura organizacional que promueve la capacitaci\u00f3n continua, la igualdad de oportunidades y la innovaci\u00f3n como pilares fundamentales para el crecimiento.<\/p>\n\n\n\n<p>&lt;&gt;, destac\u00f3 Javier Carrizo Esquivel, gerente general de la instituci\u00f3n bancaria.<br>Merco combina encuestas a colaboradores, j\u00f3venes profesionales, consultores de recursos humanos y expertos en captaci\u00f3n de talento, junto con un profundo an\u00e1lisis reputacional. La ubicaci\u00f3n de Banconal dentro del Top 3 nacional demuestra coherencia y evoluci\u00f3n en la gesti\u00f3n del talento frente a las mejores organizaciones del pa\u00eds.<\/p>\n\n\n\n<p>\u201cEl Banco de todos los paname\u00f1os continuar\u00e1 fortaleciendo programas como gu\u00eda profesional especializada, capacitaci\u00f3n digital y herramientas de bienestar, para construir juntos un lugar de crecimiento laboral con prop\u00f3sito\u201d, se\u00f1al\u00f3 Carrizo Esquivel.<\/p>\n\n\n\n<p>Sobre el Monitor Merco Talento: Se trata de una de las principales herramientas de medici\u00f3n frente a l\u00edderes del mercado de Iberoam\u00e9rica, auditada por KPMG y basada en la percepci\u00f3n de m\u00e1s de 7\u202f000 encuestados, incluyendo empleados, universitarios, expertos en recursos humanos y poblaci\u00f3n general.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-400\" srcset=\"https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1-1024x682.jpeg 1024w, https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1-300x200.jpeg 300w, https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1-768x512.jpeg 768w, https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1-1536x1023.jpeg 1536w, https:\/\/visioninforma.com\/portal\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-26-at-10.31.56-AM-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Con este 2do. lugar en el ranking Merco Talento, la instituci\u00f3n bancaria sube tres posiciones si lo comparamos con el ranking 2024, donde alcanz\u00f3 la 5ta. posici\u00f3n. Panam\u00e1, 26 de junio de 2025. La primera instituci\u00f3n bancaria del pa\u00eds, consolida su liderazgo en la gesti\u00f3n del talento al posicionarse dentro del Top 3 de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,32,23],"tags":[],"class_list":["post-398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-negocios","category-noticias"],"_links":{"self":[{"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/posts\/398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":1,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"predecessor-version":[{"id":401,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/posts\/398\/revisions\/401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/media\/400"}],"wp:attachment":[{"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visioninforma.com\/portal\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}